{"id":222,"date":"2024-12-20T17:49:32","date_gmt":"2024-12-20T16:49:32","guid":{"rendered":"http:\/\/riadabadi.com\/?page_id=222"},"modified":"2025-11-01T22:33:08","modified_gmt":"2025-11-01T21:33:08","slug":"activites-a-fes","status":"publish","type":"page","link":"https:\/\/riadabadi.com\/index.php\/activites-a-fes\/","title":{"rendered":"Que voir \u00e0 F\u00e8s"},"content":{"rendered":"\r\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Evoluez au coeur d&#8217;une cit\u00e9 m\u00e9di\u00e9vale encore en activit\u00e9<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-align: justify;\">La vieille ville de F\u00e8s, la m\u00e9dina, est le plus grand environnement urbain sans voitures au monde ! La mani\u00e8re dont vivent les gens ici n\u2019a pas vraiment chang\u00e9 depuis des si\u00e8cles. Le spectacle est dans la rue. Faites attention aux d\u00e9tails, la mani\u00e8re dont les gens s\u2019habillent, ce qu\u2019ils font, leur comportement\u2026 M\u00eame si tout va vite en ce d\u00e9but de XXI\u00e8me si\u00e8cle, ce que vous voyez ici est encore r\u00e9ellement authentique. M\u00eame si la m\u00e9dina a besoin du tourisme, l\u2019activit\u00e9 ici repose essentiellement sur un r\u00e9seau de centaines de petits commer\u00e7ants et artisans qui sont interd\u00e9pendants. C\u2019est probablement gr\u00e2ce \u00e0 cela que survit cette fantastique cit\u00e9 m\u00e9di\u00e9vale.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-align: justify;\"><strong>L&#8217;emplacement de notre riad ne peut \u00eatre plus id\u00e9al <\/strong>: en plein centre de la m\u00e9dina, \u00e0 proximit\u00e9 des points d&#8217;int\u00e9r\u00eats mais dans une impasse au calme ! La m\u00e9dina de F\u00e8s compte plus de 9000 rues; elle est un labyrinthe complexe, constitu\u00e9 de passages \u00e9troits, de petites all\u00e9es mais aussi de grandes art\u00e8res commer\u00e7antes. Ce r\u00e9seau enchev\u00eatr\u00e9 en fait l&#8217;un des environnements urbains historiques les plus denses et fascinants au monde. L&#8217;office de tourisme de F\u00e8s propose d&#8217;ailleurs 6 circuits touristiques, identifi\u00e9s avec des couleurs, selon des th\u00e9matiques comme &#8220;monuments et souks&#8221; ou encore &#8220;artisanat&#8221;&#8230;<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-spacer\" style=\"height: 22px;\" aria-hidden=\"true\">\u00a0<\/div>\r\n\r\n\r\n\r\n<div class=\"is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\u00a0<\/div>\r\n<div>\r\n<style type=\"text\/css\">\n#foogallery-gallery-621.fg-simple_portfolio { justify-content: center; --fg-gutter: 5px; }\n#foogallery-gallery-621.fg-simple_portfolio .fg-item { flex-basis: 250px; }<\/style>\n\t\t\t<div class=\"foogallery foogallery-container foogallery-simple_portfolio foogallery-lightbox-none fg-simple_portfolio fg-ready fg-dark fg-border-thin fg-shadow-outline fg-loading-default fg-loaded-fade-in fg-caption-always fg-hover-fade fg-hover-external fg-caption-always\" id=\"foogallery-gallery-621\" data-foogallery=\"{&quot;item&quot;:{&quot;showCaptionTitle&quot;:true,&quot;showCaptionDescription&quot;:true},&quot;lazy&quot;:true}\" style=\"--fg-title-line-clamp: 0; --fg-description-line-clamp: 0;\" >\n\t<div class=\"fg-item fg-type-iframe fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/drive.google.com\/file\/d\/19mmvA8HebeHnQ4xuLAL-ztA4UJLypk1f\/view?usp=drive_link\" data-caption-title=\"Plan de l&#039;office du tourisme\" data-caption-desc=\"avec des parcours th\u00e9matiques\" data-attachment-id=\"622\" class=\"foogallery-thumb fg-thumb\" data-type=\"iframe\"><span class=\"fg-image-wrap\"><img fetchpriority=\"high\" decoding=\"async\" title=\"Plan de l&#039;office du tourisme\" class=\"bf-img skip-lazy fg-image\" height=\"200\" width=\"250\" data-src-fg=\"https:\/\/riadabadi.com\/wp-content\/uploads\/cache\/2025\/11\/plan-avec-parcours\/995366370.png\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22250%22%20height%3D%22200%22%20viewBox%3D%220%200%20250%20200%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-title\">Plan de l'office du tourisme<\/div><div class=\"fg-caption-desc\">avec des parcours th\u00e9matiques<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-iframe fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/www.google.com\/maps\/d\/u\/0\/edit?mid=15wvuOkTFqvgFDXDZbgTqzFsvJARcCQU&amp;usp=sharing\" target=\"_blank\" data-caption-title=\"Plan int\u00e9ractif\" data-caption-desc=\"avec nos recommandations de visites et restaurants\" data-attachment-id=\"623\" class=\"foogallery-thumb fg-thumb\" data-type=\"iframe\"><span class=\"fg-image-wrap\"><img decoding=\"async\" title=\"Plan int\u00e9ractif\" class=\"bf-img skip-lazy fg-image\" height=\"200\" width=\"250\" data-src-fg=\"https:\/\/riadabadi.com\/wp-content\/uploads\/cache\/2025\/11\/plan-interactif\/3409049645.png\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22250%22%20height%3D%22200%22%20viewBox%3D%220%200%20250%20200%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-title\">Plan int\u00e9ractif<\/div><div class=\"fg-caption-desc\">avec nos recommandations de visites et restaurants<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-spacer\" style=\"height: 35px;\" aria-hidden=\"true\">\u00a0<\/div>\r\n\r\n\r\n\r\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"text-align: justify;\">Nous recommandons de prendre un <strong>guide officiel<\/strong> la premi\u00e8re journ\u00e9e ou au moins une demi journ\u00e9e. Nous avons fait une s\u00e9lection de bons guides passionn\u00e9s par leur m\u00e9tier et la m\u00e9dina de F\u00e8s. Ils ne vous pousseront pas dans les magasins mais se contenteront de vous faire d\u00e9couvrir la magie de F\u00e8s ! Pour la visite de la ville, les prix planchers \u00e0 partir de F\u00e9vrier 2025 sont de 500 Dh la demi-journ\u00e9e pour un groupe de moins de 10 personnes, 800 Dhs la journ\u00e9e.\u00a0<\/p>\r\n<p><strong><span style=\"text-decoration: underline;\">Quelques \u00e9l\u00e9ments \u00e0 savoir quand on se prom\u00e8ne dans la m\u00e9dina :\u00a0<\/span><\/strong><br \/><br \/><\/p>\r\n<blockquote>\r\n<p>Les panneaux rectangulaires annoncent des rues. Si vous voyez un panneau hexagonal, c&#8217;est que c&#8217;est une impasse !<\/p>\r\n<\/blockquote>\r\n<p style=\"text-align: center;\">\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-490\" src=\"https:\/\/riadabadi.com\/wp-content\/uploads\/2025\/02\/rue-300x294.png\" alt=\"\" width=\"202\" height=\"198\" srcset=\"https:\/\/riadabadi.com\/wp-content\/uploads\/2025\/02\/rue-300x294.png 300w, https:\/\/riadabadi.com\/wp-content\/uploads\/2025\/02\/rue-357x350.png 357w, https:\/\/riadabadi.com\/wp-content\/uploads\/2025\/02\/rue.png 381w\" sizes=\"auto, (max-width: 202px) 100vw, 202px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-492\" src=\"https:\/\/riadabadi.com\/wp-content\/uploads\/2025\/02\/impasse-1-300x285.png\" alt=\"\" width=\"208\" height=\"198\" srcset=\"https:\/\/riadabadi.com\/wp-content\/uploads\/2025\/02\/impasse-1-300x285.png 300w, https:\/\/riadabadi.com\/wp-content\/uploads\/2025\/02\/impasse-1.png 342w\" sizes=\"auto, (max-width: 208px) 100vw, 208px\" \/><\/p>\r\n<blockquote>\r\n<p>Beaucoup d&#8217;individus vous donneront votre chemin bien que vous ne l&#8217;ayez pas demand\u00e9. Ils n&#8217;ont d&#8217;ailleurs absolument aucune id\u00e9e d&#8217;o\u00f9 vous souhaitez aller puisque vous ne les avez pas sollicit\u00e9s : r\u00e9pondez juste un joyeux &#8220;ok&#8221; ou &#8220;Chokrane&#8221; et continuez votre route o\u00f9 bon vous semble !\u00a0<\/p>\r\n<\/blockquote>\r\n<p><span style=\"text-decoration: underline;\"><strong>Les incontournables de F\u00e8s :<\/strong><\/span><\/p>\r\n<p><span style=\"text-decoration: underline;\"><strong>\r\n\r\n<p><\/strong><\/span><\/p>\n<style type=\"text\/css\">\n#foogallery-gallery-298.fg-simple_portfolio { justify-content: center; --fg-gutter: 5px; }\n#foogallery-gallery-298.fg-simple_portfolio .fg-item { flex-basis: 250px; }<\/style>\n\t\t\t<div class=\"foogallery foogallery-container foogallery-simple_portfolio foogallery-lightbox-none fg-simple_portfolio fg-ready fg-light fg-border-thin fg-shadow-outline fg-loading-default fg-loaded-fade-in fg-caption-always fg-hover-fade fg-hover-external fg-c-j fg-caption-always\" id=\"foogallery-gallery-298\" data-foogallery=\"{&quot;item&quot;:{&quot;showCaptionTitle&quot;:true,&quot;showCaptionDescription&quot;:true},&quot;lazy&quot;:true,&quot;paging&quot;:{&quot;type&quot;:&quot;dots&quot;,&quot;size&quot;:20,&quot;position&quot;:&quot;bottom&quot;,&quot;scrollToTop&quot;:false,&quot;output&quot;:&quot;&quot;,&quot;theme&quot;:&quot;fg-light&quot;}}\" style=\"--fg-title-line-clamp: 0; --fg-description-line-clamp: 0;\" >\n\t<div class=\"fg-item fg-type-iframe fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/www.google.com\/maps\/dir\/Place+Seffarine,+F%C3%A8s\/Riad+Abadi,+quartier+Kettanine,+8+rue+derb+laakiba,+Fes\/@34.0639007,-4.9751801,17.59z\/data=!4m14!4m13!1m5!1m1!1s0xd9ff359dfd40ff1:0x166cc10f0b6fe712!2m2!1d-4.9727747!2d34.0641964!1m5!1m1!1s0xd9ff33946b8be71:0xad8bc8f3f58dfadf!2m2!1d-4.9750805!2d34.0630946!3e2?entry=ttu&amp;g_ep=EgoyMDI1MDExMC4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" data-caption-title=\"M\u00e9dina\" data-caption-desc=\"La m\u00e9dina de F\u00e8s, inscrite au patrimoine mondial de l\u2019UNESCO, est un tr\u00e9sor historique o\u00f9 chaque ruelle r\u00e9v\u00e8le l&#039;authenticit\u00e9 du Maroc. Ce labyrinthe m\u00e9di\u00e9val regorge de mosqu\u00e9es anciennes, d\u2019artisanat s\u00e9culaire et de march\u00e9s anim\u00e9s, parfaits pour d\u00e9nicher une djellaba ou une gandoura.\" data-attachment-id=\"310\" class=\"foogallery-thumb fg-thumb\" data-type=\"iframe\"><span class=\"fg-image-wrap\"><img decoding=\"async\" title=\"M\u00e9dina\" class=\"bf-img skip-lazy fg-image\" height=\"200\" width=\"250\" data-src-fg=\"https:\/\/riadabadi.com\/wp-content\/uploads\/cache\/2024\/12\/medina\/2227936756.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22250%22%20height%3D%22200%22%20viewBox%3D%220%200%20250%20200%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-title\">M\u00e9dina<\/div><div class=\"fg-caption-desc\">La m\u00e9dina de F\u00e8s, inscrite au patrimoine mondial de l\u2019UNESCO, est un tr\u00e9sor historique o\u00f9 chaque ruelle r\u00e9v\u00e8le l'authenticit\u00e9 du Maroc. Ce labyrinthe m\u00e9di\u00e9val regorge de mosqu\u00e9es anciennes, d\u2019artisanat s\u00e9culaire et de march\u00e9s anim\u00e9s, parfaits pour d\u00e9nicher une djellaba ou une gandoura.<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-iframe fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/www.google.com\/maps\/dir\/Riad+Abadi,+F%C3%A8s\/327G%2BX6Q+Kissariat+al-Kifah,+Rue+Talaa+Kebira,+F%C3%A8s\/@34.0643183,-4.9757427,17.68z\/data=!4m14!4m13!1m5!1m1!1s0xd9ff33946b8be71:0xad8bc8f3f58dfadf!2m2!1d-4.9750805!2d34.0630946!1m5!1m1!1s0xd9ff366040dca7b:0x4671dee99605f501!2m2!1d-4.9743803!2d34.0649564!3e2?entry=ttu&amp;g_ep=EgoyMDI1MDExMC4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" data-caption-title=\"Souk\" data-caption-desc=\"Les souks offrent une immersion authentique dans la culture et l\u2019artisanat local. Ces march\u00e9s anim\u00e9s regroupent souvent des corporations. Le plus ancien se nomme Kiseria Al Kifah.\" data-attachment-id=\"308\" class=\"foogallery-thumb fg-thumb\" data-type=\"iframe\"><span class=\"fg-image-wrap\"><img decoding=\"async\" title=\"Souk\" class=\"bf-img skip-lazy fg-image\" height=\"200\" width=\"250\" data-src-fg=\"https:\/\/riadabadi.com\/wp-content\/uploads\/cache\/2024\/12\/souk\/346726386.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22250%22%20height%3D%22200%22%20viewBox%3D%220%200%20250%20200%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-title\">Souk<\/div><div class=\"fg-caption-desc\">Les souks offrent une immersion authentique dans la culture et l\u2019artisanat local. Ces march\u00e9s anim\u00e9s regroupent souvent des corporations. Le plus ancien se nomme Kiseria Al Kifah.<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/riadabadi.com\/wp-content\/uploads\/2024\/12\/IMG_20260223_135926.jpg\" data-caption-desc=\"Les tanneurs de cuir forment une cat\u00e9gorie unique dans les souks, marquant les visiteurs par l\u2019odeur intense qui impr\u00e8gne leurs ateliers. Pour les non-initi\u00e9s, cette odeur peut surprendre. La tannerie Chouara est la plus impressionnante. Petit conseil : emportez quelques feuilles de menthe pour supporter l&#039;odeur !\" data-attachment-id=\"646\" class=\"foogallery-thumb fg-thumb\" data-type=\"image\"><span class=\"fg-image-wrap\"><img decoding=\"async\" class=\"bf-img skip-lazy fg-image\" height=\"200\" width=\"250\" data-src-fg=\"https:\/\/riadabadi.com\/wp-content\/uploads\/cache\/2024\/12\/IMG_20260223_135926\/1125114552.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22250%22%20height%3D%22200%22%20viewBox%3D%220%200%20250%20200%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Les tanneurs de cuir forment une cat\u00e9gorie unique dans les souks, marquant les visiteurs par l\u2019odeur intense qui impr\u00e8gne leurs ateliers. Pour les non-initi\u00e9s, cette odeur peut surprendre. La tannerie Chouara est la plus impressionnante. Petit conseil : emportez quelques feuilles de menthe pour supporter l'odeur !<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-iframe fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/www.google.com\/maps\/dir\/Riad+Abadi,+F%C3%A8s\/Mosqu%C3%A9e+et+Universit%C3%A9+Karaouiyne,+F%C3%A8s\/@34.064097,-4.9768387,17z\/data=!3m1!4b1!4m14!4m13!1m5!1m1!1s0xd9ff33946b8be71:0xad8bc8f3f58dfadf!2m2!1d-4.9750805!2d34.0630946!1m5!1m1!1s0xd9ff359c4e30d3f:0x8614a8beafd0df83!2m2!1d-4.9733667!2d34.0649299!3e2?entry=ttu&amp;g_ep=EgoyMDI1MDExMC4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" data-caption-title=\"Universit\u00e9 et Mosqu\u00e9e Karaouiyne\" data-caption-desc=\"Fond\u00e9e en 859, cette universit\u00e9, la plus ancienne du monde arabe, demeure un centre spirituel. Bien que l\u2019entr\u00e9e soit r\u00e9serv\u00e9e aux musulmans, ses ext\u00e9rieurs sont \u00e0 d\u00e9couvrir, avec leurs d\u00e9tails raffin\u00e9s, ses 270 colonnes et 24 portes entourant une cour int\u00e9rieure.\" data-attachment-id=\"306\" class=\"foogallery-thumb fg-thumb\" data-type=\"iframe\"><span class=\"fg-image-wrap\"><img decoding=\"async\" title=\"Universit\u00e9 et Mosqu\u00e9e Karaouiyne\" class=\"bf-img skip-lazy fg-image\" height=\"200\" width=\"250\" data-src-fg=\"https:\/\/riadabadi.com\/wp-content\/uploads\/cache\/2024\/12\/800px-University_of_Al_Qaraouiyine\/1595981036.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22250%22%20height%3D%22200%22%20viewBox%3D%220%200%20250%20200%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-title\">Universit\u00e9 et Mosqu\u00e9e Karaouiyne<\/div><div class=\"fg-caption-desc\">Fond\u00e9e en 859, cette universit\u00e9, la plus ancienne du monde arabe, demeure un centre spirituel. Bien que l\u2019entr\u00e9e soit r\u00e9serv\u00e9e aux musulmans, ses ext\u00e9rieurs sont \u00e0 d\u00e9couvrir, avec leurs d\u00e9tails raffin\u00e9s, ses 270 colonnes et 24 portes entourant une cour int\u00e9rieure.<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-iframe fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/www.google.com\/maps\/dir\/Place+Seffarine,+F%C3%A8s\/Riad+Abadi,+quartier+Kettanine,+8+rue+derb+laakiba,+Fes\/@34.0639007,-4.9751801,17.59z\/data=!4m14!4m13!1m5!1m1!1s0xd9ff359dfd40ff1:0x166cc10f0b6fe712!2m2!1d-4.9727747!2d34.0641964!1m5!1m1!1s0xd9ff33946b8be71:0xad8bc8f3f58dfadf!2m2!1d-4.9750805!2d34.0630946!3e2?entry=ttu&amp;g_ep=EgoyMDI1MDExMC4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" data-caption-title=\"Place Seffarine\" data-caption-desc=\"La place Seffarine, nich\u00e9e au c\u0153ur de la m\u00e9dina, est un lieu incontournable pour d\u00e9couvrir un artisanat traditionnel marocain particulier : c\u00e9l\u00e8bre pour ses artisans-dinandiers, on y trouve des cr\u00e9ateurs de th\u00e9i\u00e8res, plateaux, br\u00fble-parfums, ainsi que des chaudronniers travaillant marmites et seaux. Une immersion inoubliable dans le savoir-faire du cuivre martel\u00e9 avec une dext\u00e9rit\u00e9 exceptionnelle.\" data-attachment-id=\"305\" class=\"foogallery-thumb fg-thumb\" data-type=\"iframe\"><span class=\"fg-image-wrap\"><img decoding=\"async\" title=\"Place Seffarine\" class=\"bf-img skip-lazy fg-image\" height=\"200\" width=\"250\" data-src-fg=\"https:\/\/riadabadi.com\/wp-content\/uploads\/cache\/2024\/12\/place-seffarine\/4117566020.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22250%22%20height%3D%22200%22%20viewBox%3D%220%200%20250%20200%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-title\">Place Seffarine<\/div><div class=\"fg-caption-desc\">La place Seffarine, nich\u00e9e au c\u0153ur de la m\u00e9dina, est un lieu incontournable pour d\u00e9couvrir un artisanat traditionnel marocain particulier : c\u00e9l\u00e8bre pour ses artisans-dinandiers, on y trouve des cr\u00e9ateurs de th\u00e9i\u00e8res, plateaux, br\u00fble-parfums, ainsi que des chaudronniers travaillant marmites et seaux. Une immersion inoubliable dans le savoir-faire du cuivre martel\u00e9 avec une dext\u00e9rit\u00e9 exceptionnelle.<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-iframe fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/www.google.com\/maps\/dir\/Riad+Abadi,+F%C3%A8s\/M%C3%A9dersa+Attarine,+Rue+Talaa+Kebira,+F%C3%A8s\/Saffarin+Madrasa,+F%C3%A8s\/@34.0642309,-4.9762143,17z\/data=!4m20!4m19!1m5!1m1!1s0xd9ff33946b8be71:0xad8bc8f3f58dfadf!2m2!1d-4.9750805!2d34.0630946!1m5!1m1!1s0xd9ff359ca2f5575:0x694d0781fb7d3f1f!2m2!1d-4.9736165!2d34.0651253!1m5!1m1!1s0xd9ff343d6c1757f:0x20bd0e5a25f0005f!2m2!1d-4.9726114!2d34.0641466!3e2?entry=ttu&amp;g_ep=EgoyMDI1MDExMC4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" data-caption-title=\"Medersa\" data-caption-desc=\"Les m\u00e9dersas, anciennes \u00e9coles coraniques et internats, sont nombreuses \u00e0 F\u00e8s, chacune remarquable par sa d\u00e9coration raffin\u00e9e. Parmi elles, la m\u00e9dersa Attarine, situ\u00e9e face \u00e0 la mosqu\u00e9e Karaouiyne, est r\u00e9put\u00e9e pour ses mosa\u00efques et marqueteries d\u00e9licates. La m\u00e9dersa Seffarine, fond\u00e9e en 1280, est la plus ancienne de F\u00e8s.\" data-attachment-id=\"304\" class=\"foogallery-thumb fg-thumb\" data-type=\"iframe\"><span class=\"fg-image-wrap\"><img decoding=\"async\" title=\"Medersa\" class=\"bf-img skip-lazy fg-image\" height=\"200\" width=\"250\" data-src-fg=\"https:\/\/riadabadi.com\/wp-content\/uploads\/cache\/2024\/12\/800px-Fes_Medersa_Bou_Inania_Mosaique\/4128258614.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22250%22%20height%3D%22200%22%20viewBox%3D%220%200%20250%20200%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-title\">Medersa<\/div><div class=\"fg-caption-desc\">Les m\u00e9dersas, anciennes \u00e9coles coraniques et internats, sont nombreuses \u00e0 F\u00e8s, chacune remarquable par sa d\u00e9coration raffin\u00e9e. Parmi elles, la m\u00e9dersa Attarine, situ\u00e9e face \u00e0 la mosqu\u00e9e Karaouiyne, est r\u00e9put\u00e9e pour ses mosa\u00efques et marqueteries d\u00e9licates. La m\u00e9dersa Seffarine, fond\u00e9e en 1280, est la plus ancienne de F\u00e8s.<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-iframe fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/www.google.com\/maps\/dir\/Riad+Abadi,+F%C3%A8s\/Fondouk+Nejjarine,+F%C3%A8s\/@34.0639493,-4.9777506,17z\/data=!3m1!4b1!4m14!4m13!1m5!1m1!1s0xd9ff33946b8be71:0xad8bc8f3f58dfadf!2m2!1d-4.9750805!2d34.0630946!1m5!1m1!1s0xd9ff3581109a683:0x6a46e59966ccb7bf!2m2!1d-4.9759047!2d34.0647528!3e2?entry=ttu&amp;g_ep=EgoyMDI1MDExMC4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" data-caption-title=\"Foundouk\" data-caption-desc=\"Le foundouk, ou caravans\u00e9rail, est un \u00e9difice \u00e0 \u00e9tages, construit autour d\u2019une cour carr\u00e9e. Le fondouk Nejjarine m\u00e9rite le d\u00e9tour, car il accueille aujourd\u2019hui de nombreux ateliers artisanaux.\" data-attachment-id=\"421\" class=\"foogallery-thumb fg-thumb\" data-type=\"iframe\"><span class=\"fg-image-wrap\"><img decoding=\"async\" title=\"Foundouk\" class=\"bf-img skip-lazy fg-image\" height=\"200\" width=\"250\" data-src-fg=\"https:\/\/riadabadi.com\/wp-content\/uploads\/cache\/2024\/12\/foundouk\/1360469976.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22250%22%20height%3D%22200%22%20viewBox%3D%220%200%20250%20200%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-title\">Foundouk<\/div><div class=\"fg-caption-desc\">Le foundouk, ou caravans\u00e9rail, est un \u00e9difice \u00e0 \u00e9tages, construit autour d\u2019une cour carr\u00e9e. Le fondouk Nejjarine m\u00e9rite le d\u00e9tour, car il accueille aujourd\u2019hui de nombreux ateliers artisanaux.<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-iframe fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/mda.gov.ma\/fr\/communaute-des-professionnels\/mise-en-relation-2\/region-fes-meknes\/\" target=\"_blank\" data-caption-title=\"Artisanat\" data-caption-desc=\"Ville r\u00e9put\u00e9e pour son artisanat, F\u00e8s offre des produits de grande qualit\u00e9 dont les processus artisanaux sont observables dans chaque atelier. C\u00e9ramique, cuir, cuivre, tissus, objets m\u00e9taliques, chaque pi\u00e8ce rel\u00e8ve d\u2019une tradition et d\u2019un savoir-faire, issus d\u2019un long apprentissage et d\u2019un travail minutieux. Coup de coeur pour les poteries avec leur bleu de F\u00e8s !\" data-attachment-id=\"307\" class=\"foogallery-thumb fg-thumb\" data-type=\"iframe\"><span class=\"fg-image-wrap\"><img decoding=\"async\" title=\"Artisanat\" class=\"bf-img skip-lazy fg-image\" height=\"200\" width=\"250\" data-src-fg=\"https:\/\/riadabadi.com\/wp-content\/uploads\/cache\/2024\/12\/artisanat\/394755899.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22250%22%20height%3D%22200%22%20viewBox%3D%220%200%20250%20200%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-title\">Artisanat<\/div><div class=\"fg-caption-desc\">Ville r\u00e9put\u00e9e pour son artisanat, F\u00e8s offre des produits de grande qualit\u00e9 dont les processus artisanaux sont observables dans chaque atelier. C\u00e9ramique, cuir, cuivre, tissus, objets m\u00e9taliques, chaque pi\u00e8ce rel\u00e8ve d\u2019une tradition et d\u2019un savoir-faire, issus d\u2019un long apprentissage et d\u2019un travail minutieux. Coup de coeur pour les poteries avec leur bleu de F\u00e8s !<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/riadabadi.com\/wp-content\/uploads\/2024\/12\/P2231653_edit_215469615595200.jpg\" target=\"_blank\" data-caption-title=\"Le quartier Juif\" data-caption-desc=\"Le mellah fut durant des si\u00e8cles le quartier de r\u00e9sidence de la communaut\u00e9 juive, qui choisissait de vivre \u00e0 l\u2019int\u00e9rieur de l\u2019enceinte fortifi\u00e9e du palais afin de b\u00e9n\u00e9ficier de la protection des sultans, tout en d\u00e9tenant notamment le monopole du commerce des m\u00e9taux pr\u00e9cieux. Aujourd\u2019hui int\u00e9gr\u00e9 au reste de la ville, il conserve pourtant ses sp\u00e9cificit\u00e9s architecturales \u2014 comme les balcons ext\u00e9rieurs en fer forg\u00e9 \u2014 que l\u2019on d\u00e9couvre en parcourant la rue Mellah et ses ruelles autrefois anim\u00e9es par de riches march\u00e9s de tissus.\" data-attachment-id=\"647\" class=\"foogallery-thumb fg-thumb\" data-type=\"image\"><span class=\"fg-image-wrap\"><img decoding=\"async\" title=\"Le quartier Juif\" class=\"bf-img skip-lazy fg-image\" height=\"200\" width=\"250\" data-src-fg=\"https:\/\/riadabadi.com\/wp-content\/uploads\/cache\/2024\/12\/P2231653_edit_215469615595200\/2645258287.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22250%22%20height%3D%22200%22%20viewBox%3D%220%200%20250%20200%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-title\">Le quartier Juif<\/div><div class=\"fg-caption-desc\">Le mellah fut durant des si\u00e8cles le quartier de r\u00e9sidence de la communaut\u00e9 juive, qui choisissait de vivre \u00e0 l\u2019int\u00e9rieur de l\u2019enceinte fortifi\u00e9e du palais afin de b\u00e9n\u00e9ficier de la protection des sultans, tout en d\u00e9tenant notamment le monopole du commerce des m\u00e9taux pr\u00e9cieux. Aujourd\u2019hui int\u00e9gr\u00e9 au reste de la ville, il conserve pourtant ses sp\u00e9cificit\u00e9s architecturales \u2014 comme les balcons ext\u00e9rieurs en fer forg\u00e9 \u2014 que l\u2019on d\u00e9couvre en parcourant la rue Mellah et ses ruelles autrefois anim\u00e9es par de riches march\u00e9s de tissus.<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-iframe fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/www.lavieeco.com\/influences\/culture\/fes-la-cite-a-travers-ses-grandes-portes\/\" target=\"_blank\" data-caption-title=\"Portes de la m\u00e9dina\" data-caption-desc=\"Les portes de F\u00e8s, ou bab, sont bien plus que des points d&#039;acc\u00e8s : elles incarnent des si\u00e8cles d\u2019histoire et d\u2019architecture. Bab BouJeloud, la porte principale orn\u00e9e de fa\u00efences bleues et vertes, et Bab Dekkakin, \u00e0 l&#039;allure de ch\u00e2teau m\u00e9di\u00e9val, sont des incontournables. Chaque porte raconte une part de l&#039;\u00e9volution de cette cit\u00e9 imp\u00e9riale.\" data-attachment-id=\"302\" class=\"foogallery-thumb fg-thumb\" data-type=\"iframe\"><span class=\"fg-image-wrap\"><img decoding=\"async\" title=\"Portes de la m\u00e9dina\" class=\"bf-img skip-lazy fg-image\" height=\"200\" width=\"250\" data-src-fg=\"https:\/\/riadabadi.com\/wp-content\/uploads\/cache\/2024\/12\/bab\/2119420905.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22250%22%20height%3D%22200%22%20viewBox%3D%220%200%20250%20200%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-title\">Portes de la m\u00e9dina<\/div><div class=\"fg-caption-desc\">Les portes de F\u00e8s, ou bab, sont bien plus que des points d'acc\u00e8s : elles incarnent des si\u00e8cles d\u2019histoire et d\u2019architecture. Bab BouJeloud, la porte principale orn\u00e9e de fa\u00efences bleues et vertes, et Bab Dekkakin, \u00e0 l'allure de ch\u00e2teau m\u00e9di\u00e9val, sont des incontournables. Chaque porte raconte une part de l'\u00e9volution de cette cit\u00e9 imp\u00e9riale.<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-iframe fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/www.google.com\/maps\/dir\/Riad+Abadi,+F%C3%A8s\/Dar+al-Magana+(Water+Clock),+Rue+Talaa+Kebira,+F%C3%A8s\/@34.0633647,-4.9814959,17z\/data=!3m1!4b1!4m14!4m13!1m5!1m1!1s0xd9ff33946b8be71:0xad8bc8f3f58dfadf!2m2!1d-4.9751608!2d34.0630825!1m5!1m1!1s0xd9ff5d695aeda6f:0xb2b640d2a49490bb!2m2!1d-4.9829146!2d34.0623852!3e2!5m1!1e1?entry=ttu&amp;g_ep=EgoyMDI1MDMwMy4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" data-caption-title=\"Horloge Bouinaniyya de F\u00e8s\" data-caption-desc=\"Cette horloge, construite au XIVe si\u00e8cle sous les M\u00e9rinides, est une horloge hydraulique situ\u00e9e \u00e0 l\u2019entr\u00e9e de la m\u00e9dersa Bou Inania. Jadis utilis\u00e9e pour mesurer le temps et rythmer les pri\u00e8res, elle t\u00e9moigne du savoir-faire scientifique et artisanal de l\u2019\u00e9poque. Son m\u00e9canisme est toujours myst\u00e9rieux.\" data-attachment-id=\"554\" class=\"foogallery-thumb fg-thumb\" data-type=\"iframe\"><span class=\"fg-image-wrap\"><img decoding=\"async\" title=\"Horloge Bouinaniyya de F\u00e8s\" class=\"bf-img skip-lazy fg-image\" height=\"200\" width=\"250\" data-src-fg=\"https:\/\/riadabadi.com\/wp-content\/uploads\/cache\/2024\/12\/20250105_180053-scaled\/3297875292.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22250%22%20height%3D%22200%22%20viewBox%3D%220%200%20250%20200%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-title\">Horloge Bouinaniyya de F\u00e8s<\/div><div class=\"fg-caption-desc\">Cette horloge, construite au XIVe si\u00e8cle sous les M\u00e9rinides, est une horloge hydraulique situ\u00e9e \u00e0 l\u2019entr\u00e9e de la m\u00e9dersa Bou Inania. Jadis utilis\u00e9e pour mesurer le temps et rythmer les pri\u00e8res, elle t\u00e9moigne du savoir-faire scientifique et artisanal de l\u2019\u00e9poque. Son m\u00e9canisme est toujours myst\u00e9rieux.<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-iframe fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/www.google.com\/maps\/dir\/Riad+Abadi,+F%C3%A8s\/Mus%C3%A9e+batha,+Oued+Fejjaline%D8%8C+5+Ave+du+Batha,+F%C3%A8s%E2%80%AD\/@34.0619889,-4.9813988,17z\/data=!3m1!4b1!4m14!4m13!1m5!1m1!1s0xd9ff33946b8be71:0xad8bc8f3f58dfadf!2m2!1d-4.9751608!2d34.0630825!1m5!1m1!1s0xd9ff4aed90b70d3:0xc44a61c2c91a5c87!2m2!1d-4.9826708!2d34.0605506!3e2!5m1!1e1?entry=ttu&amp;g_ep=EgoyMDI1MDIyNi4xIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" data-caption-title=\"Mus\u00e9e Al Batha\" data-caption-desc=\"Ce magnifique palais avec son jardin luxuriant met en lumi\u00e8re la richesse culturelle marocaine \u00e0 travers un parcours historique et th\u00e9matique tr\u00e8s bien pens\u00e9 et am\u00e9nag\u00e9.  700 objets sont pr\u00e9sent\u00e9s et, parmi eux, des pi\u00e8ces rares des arts de l&#039;Islam au Maroc, comme le tr\u00e8s ancien minbar de la mosqu\u00e9e des Andalous, t\u00e9moin des luttes entre les Fatimides et les Omeyyades ou l&#039;horloge hydraulique de la m\u00e9dersa Bou Inania dont l&#039;\u00e9nigmatique m\u00e9canisme t\u00e9moigne du haut degr\u00e9 d&#039;ing\u00e9niosit\u00e9 des savants de l&#039;\u00e9poque.\" data-attachment-id=\"559\" class=\"foogallery-thumb fg-thumb\" data-type=\"iframe\"><span class=\"fg-image-wrap\"><img decoding=\"async\" title=\"Mus\u00e9e Al Batha\" class=\"bf-img skip-lazy fg-image\" height=\"200\" width=\"250\" data-src-fg=\"https:\/\/riadabadi.com\/wp-content\/uploads\/cache\/2024\/12\/WhatsApp-Image-2025-03-01-a-19_15_04_4acba019\/2995793617.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22250%22%20height%3D%22200%22%20viewBox%3D%220%200%20250%20200%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-title\">Mus\u00e9e Al Batha<\/div><div class=\"fg-caption-desc\">Ce magnifique palais avec son jardin luxuriant met en lumi\u00e8re la richesse culturelle marocaine \u00e0 travers un parcours historique et th\u00e9matique tr\u00e8s bien pens\u00e9 et am\u00e9nag\u00e9.  700 objets sont pr\u00e9sent\u00e9s et, parmi eux, des pi\u00e8ces rares des arts de l'Islam au Maroc, comme le tr\u00e8s ancien minbar de la mosqu\u00e9e des Andalous, t\u00e9moin des luttes entre les Fatimides et les Omeyyades ou l'horloge hydraulique de la m\u00e9dersa Bou Inania dont l'\u00e9nigmatique m\u00e9canisme t\u00e9moigne du haut degr\u00e9 d'ing\u00e9niosit\u00e9 des savants de l'\u00e9poque.<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-iframe fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/www.google.com\/maps\/dir\/Riad+Abadi,+F%C3%A8s\/Vichy+Thermalia+Spa+H%C3%B4tel+Moulay+Yacoub+Fes,+F%C3%A8s\/@34.0968943,-5.1627669,12z\/data=!3m1!4b1!4m14!4m13!1m5!1m1!1s0xd9ff33946b8be71:0xad8bc8f3f58dfadf!2m2!1d-4.9750805!2d34.0630946!1m5!1m1!1s0xda019aa82f891e9:0x7af4c43285225bae!2m2!1d-5.1848452!2d34.0904716!3e0?entry=ttu&amp;g_ep=EgoyMDI1MDExMC4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" data-caption-title=\"Plus loin : Station thermale\" data-caption-desc=\"\u00c0 20 km de F\u00e8s, la station thermale de Moulay Yacoub est c\u00e9l\u00e8bre pour les vertus de ses eaux sulfureuses, qui jaillissent d&#039;une source situ\u00e9e \u00e0 1500 m\u00e8tres de profondeur \u00e0 une temp\u00e9rature de 52\u00b0C.  Cette eau hyperthermale offre de nombreux bienfaits : ses propri\u00e9t\u00e9s apaisent les rhumatismes, les affections ORL (nez et gorge), les maladies de la peau et certains troubles gyn\u00e9cologiques. A noter : pr\u00e8s de Mekn\u00e8s, la source chaude Ain Salama, sans souffre mais \u00e0 39\u00b0 propose un hammam et des piscines \u00e9galement !\" data-attachment-id=\"420\" class=\"foogallery-thumb fg-thumb\" data-type=\"iframe\"><span class=\"fg-image-wrap\"><img decoding=\"async\" title=\"Plus loin : Station thermale\" class=\"bf-img skip-lazy fg-image\" height=\"200\" width=\"250\" data-src-fg=\"https:\/\/riadabadi.com\/wp-content\/uploads\/cache\/2024\/12\/moulay-yacoub\/2184791456.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22250%22%20height%3D%22200%22%20viewBox%3D%220%200%20250%20200%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-title\">Plus loin : Station thermale<\/div><div class=\"fg-caption-desc\">\u00c0 20 km de F\u00e8s, la station thermale de Moulay Yacoub est c\u00e9l\u00e8bre pour les vertus de ses eaux sulfureuses, qui jaillissent d'une source situ\u00e9e \u00e0 1500 m\u00e8tres de profondeur \u00e0 une temp\u00e9rature de 52\u00b0C.  Cette eau hyperthermale offre de nombreux bienfaits : ses propri\u00e9t\u00e9s apaisent les rhumatismes, les affections ORL (nez et gorge), les maladies de la peau et certains troubles gyn\u00e9cologiques. A noter : pr\u00e8s de Mekn\u00e8s, la source chaude Ain Salama, sans souffre mais \u00e0 39\u00b0 propose un hammam et des piscines \u00e9galement !<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-iframe fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/www.google.com\/maps\/dir\/Riad+Abadi,+F%C3%A8s\/Azrou\/@33.8171388,-5.4700545,9.69z\/data=!4m14!4m13!1m5!1m1!1s0xd9ff33946b8be71:0xad8bc8f3f58dfadf!2m2!1d-4.9750805!2d34.0630946!1m5!1m1!1s0xda1db356fb826b3:0xb4f27cf230f6e50b!2m2!1d-5.2318879!2d33.4347305!3e0?entry=ttu&amp;g_ep=EgoyMDI1MDExMC4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" data-caption-title=\"Plus loin : Azrou\" data-caption-desc=\"Azrou, situ\u00e9e \u00e0 environ une heure de F\u00e8s, est une charmante ville montagnarde connue pour ses for\u00eats de c\u00e8dres et ses singes magots.\" data-attachment-id=\"299\" class=\"foogallery-thumb fg-thumb\" data-type=\"iframe\"><span class=\"fg-image-wrap\"><img decoding=\"async\" title=\"Plus loin : Azrou\" class=\"bf-img skip-lazy fg-image\" height=\"200\" width=\"250\" data-src-fg=\"https:\/\/riadabadi.com\/wp-content\/uploads\/cache\/2024\/12\/singe\/3599774173.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22250%22%20height%3D%22200%22%20viewBox%3D%220%200%20250%20200%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-title\">Plus loin : Azrou<\/div><div class=\"fg-caption-desc\">Azrou, situ\u00e9e \u00e0 environ une heure de F\u00e8s, est une charmante ville montagnarde connue pour ses for\u00eats de c\u00e8dres et ses singes magots.<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-iframe fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/www.google.com\/maps\/dir\/Riad+Abadi,+F%C3%A8s\/Volubilis+archaeological+site,+Fertassa\/@34.1336999,-5.5933975,10z\/data=!3m1!4b1!4m14!4m13!1m5!1m1!1s0xd9ff33946b8be71:0xad8bc8f3f58dfadf!2m2!1d-4.9750805!2d34.0630946!1m5!1m1!1s0xda06930f477a25f:0x63b79ee42ba76d67!2m2!1d-5.5523387!2d34.0719819!3e0?entry=ttu&amp;g_ep=EgoyMDI1MDExMC4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" data-caption-title=\"Plus loin : Volubilis\" data-caption-desc=\"\u00c0 seulement 45 minutes de F\u00e8s, Volubilis est un site arch\u00e9ologique fascinant class\u00e9 au patrimoine mondial de l&#039;UNESCO. Ancienne capitale romaine, elle se distingue par ses magnifiques ruines, notamment des mosa\u00efques bien pr\u00e9serv\u00e9es et un impressionnant arc de triomphe.\" data-attachment-id=\"300\" class=\"foogallery-thumb fg-thumb\" data-type=\"iframe\"><span class=\"fg-image-wrap\"><img decoding=\"async\" title=\"Plus loin : Volubilis\" class=\"bf-img skip-lazy fg-image\" height=\"200\" width=\"250\" data-src-fg=\"https:\/\/riadabadi.com\/wp-content\/uploads\/cache\/2024\/12\/1024px-Volubilisjs9\/599699192.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22250%22%20height%3D%22200%22%20viewBox%3D%220%200%20250%20200%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-title\">Plus loin : Volubilis<\/div><div class=\"fg-caption-desc\">\u00c0 seulement 45 minutes de F\u00e8s, Volubilis est un site arch\u00e9ologique fascinant class\u00e9 au patrimoine mondial de l'UNESCO. Ancienne capitale romaine, elle se distingue par ses magnifiques ruines, notamment des mosa\u00efques bien pr\u00e9serv\u00e9es et un impressionnant arc de triomphe.<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-iframe fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/www.google.com\/maps\/dir\/Riad+Abadi,+F%C3%A8s\/Mekn%C3%A8s\/@33.9460474,-5.5882849,10z\/data=!3m1!4b1!4m14!4m13!1m5!1m1!1s0xd9ff33946b8be71:0xad8bc8f3f58dfadf!2m2!1d-4.9750805!2d34.0630946!1m5!1m1!1s0xda044d23bfc49d1:0xfbbf80a99e4cde18!2m2!1d-5.5382116!2d33.8674514!3e0?entry=ttu&amp;g_ep=EgoyMDI1MDExMC4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" data-caption-title=\"Plus loin : Mekn\u00e8s\" data-caption-desc=\"Situ\u00e9e \u00e0 seulement une heure de route de F\u00e8s, Mekn\u00e8s est une ville imp\u00e9riale marocaine pleine de charme, id\u00e9ale pour une excursion d\u2019une journ\u00e9e. Connue pour son patrimoine historique et ses vastes remparts, Mekn\u00e8s abrite des monuments impressionnants, tels que la majestueuse porte Bab Mansour, le mausol\u00e9e de Moulay Isma\u00efl et les greniers royaux. Son ambiance paisible et ses souks plus intimes offrent un contraste agr\u00e9able avec la m\u00e9dina anim\u00e9e de F\u00e8s !\" data-attachment-id=\"301\" class=\"foogallery-thumb fg-thumb\" data-type=\"iframe\"><span class=\"fg-image-wrap\"><img decoding=\"async\" title=\"Plus loin : Mekn\u00e8s\" class=\"bf-img skip-lazy fg-image\" height=\"200\" width=\"250\" data-src-fg=\"https:\/\/riadabadi.com\/wp-content\/uploads\/cache\/2024\/12\/meknes\/3527217353.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22250%22%20height%3D%22200%22%20viewBox%3D%220%200%20250%20200%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-title\">Plus loin : Mekn\u00e8s<\/div><div class=\"fg-caption-desc\">Situ\u00e9e \u00e0 seulement une heure de route de F\u00e8s, Mekn\u00e8s est une ville imp\u00e9riale marocaine pleine de charme, id\u00e9ale pour une excursion d\u2019une journ\u00e9e. Connue pour son patrimoine historique et ses vastes remparts, Mekn\u00e8s abrite des monuments impressionnants, tels que la majestueuse porte Bab Mansour, le mausol\u00e9e de Moulay Isma\u00efl et les greniers royaux. Son ambiance paisible et ses souks plus intimes offrent un contraste agr\u00e9able avec la m\u00e9dina anim\u00e9e de F\u00e8s !<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-iframe fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/www.google.com\/maps\/dir\/Riad+Abadi,+quartier+Kettanine,+8+rue+derb+laakiba,+Fes\/Azrou\/Q978%2BX79+Mines+of+Mibladen,+Mibladen\/3J29%2B4MX+Kasbah+Amjjouj,+%D8%A7%D9%84%D9%82%D8%AF%D9%8A%D9%85%D8%8C%E2%80%AD\/fossiles+derfoud,+Erfoud\/Merzouga+Dunes,+Merzouga\/@32.5738728,-7.2663974,7z\/data=!3m1!4b1!4m38!4m37!1m5!1m1!1s0xd9ff33946b8be71:0xad8bc8f3f58dfadf!2m2!1d-4.9751608!2d34.0630825!1m5!1m1!1s0xda1db356fb826b3:0xb4f27cf230f6e50b!2m2!1d-5.2318879!2d33.4347305!1m5!1m1!1s0xd98c5003ea6cfa1:0x29dda26f98f6169f!2m2!1d-4.6342768!2d32.7649043!1m5!1m1!1s0xd99b3fbf29bfdfd:0x22f0b5edf71e0ead!2m2!1d-4.3807651!2d32.0503641!1m5!1m1!1s0xd9764b67bb7186d:0x6fb27d4850bee474!2m2!1d-4.2263491!2d31.4507115!1m5!1m1!1s0xd973e948400d589:0x5a1c0ade6dae9b3!2m2!1d-4.0169751!2d31.1311829!3e0!5m1!1e1?entry=ttu&amp;g_ep=EgoyMDI1MDIxNy4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" data-caption-title=\"Plus loin : le d\u00e9sert\" data-caption-desc=\"Le Sahara marocain abrite l&#039;erg Chebbi, plus connu sous le nom de dunes de Merzouga, \u00e0 8h de F\u00e8s. Nous recommandons le trajet suivant : une \u00e9tape \u00e0 Azrou pour saluer les singes, une halte aux mines de Mibladen pr\u00e8s de Midelt, une visite de la kasbah Amjjouj, une chasse aux fossiles \u00e0 Erfoud et enfin les dunes de Merzouga !\" data-attachment-id=\"548\" class=\"foogallery-thumb fg-thumb\" data-type=\"iframe\"><span class=\"fg-image-wrap\"><img decoding=\"async\" title=\"Plus loin : le d\u00e9sert\" class=\"bf-img skip-lazy fg-image\" height=\"200\" width=\"250\" data-src-fg=\"https:\/\/riadabadi.com\/wp-content\/uploads\/cache\/2024\/12\/IMG-20190506-WA0011\/1992098902.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22250%22%20height%3D%22200%22%20viewBox%3D%220%200%20250%20200%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-title\">Plus loin : le d\u00e9sert<\/div><div class=\"fg-caption-desc\">Le Sahara marocain abrite l'erg Chebbi, plus connu sous le nom de dunes de Merzouga, \u00e0 8h de F\u00e8s. Nous recommandons le trajet suivant : une \u00e9tape \u00e0 Azrou pour saluer les singes, une halte aux mines de Mibladen pr\u00e8s de Midelt, une visite de la kasbah Amjjouj, une chasse aux fossiles \u00e0 Erfoud et enfin les dunes de Merzouga !<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><\/div>\n\r\n\r\n\r\n<div class=\"wp-block-spacer\" style=\"height: 39px;\" aria-hidden=\"true\">\u00a0<\/div>\r\n<div aria-hidden=\"true\">\u00a0<\/div>\r\n\r\n\r\n\r\n<ul class=\"wp-block-social-links aligncenter has-icon-color is-style-logos-only is-content-justification-center is-layout-flex wp-container-core-social-links-is-layout-fe48e5de wp-block-social-links-is-layout-flex\"><li style=\"color:#2d3142\" class=\"wp-social-link wp-social-link-instagram has-headings-color wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/www.instagram.com\/riad.abadi.fes\/profilecard\/?igsh=eGQ4Y3Y0bW9mdWM5\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12,4.622c2.403,0,2.688,0.009,3.637,0.052c0.877,0.04,1.354,0.187,1.671,0.31c0.42,0.163,0.72,0.358,1.035,0.673 c0.315,0.315,0.51,0.615,0.673,1.035c0.123,0.317,0.27,0.794,0.31,1.671c0.043,0.949,0.052,1.234,0.052,3.637 s-0.009,2.688-0.052,3.637c-0.04,0.877-0.187,1.354-0.31,1.671c-0.163,0.42-0.358,0.72-0.673,1.035 c-0.315,0.315-0.615,0.51-1.035,0.673c-0.317,0.123-0.794,0.27-1.671,0.31c-0.949,0.043-1.233,0.052-3.637,0.052 s-2.688-0.009-3.637-0.052c-0.877-0.04-1.354-0.187-1.671-0.31c-0.42-0.163-0.72-0.358-1.035-0.673 c-0.315-0.315-0.51-0.615-0.673-1.035c-0.123-0.317-0.27-0.794-0.31-1.671C4.631,14.688,4.622,14.403,4.622,12 s0.009-2.688,0.052-3.637c0.04-0.877,0.187-1.354,0.31-1.671c0.163-0.42,0.358-0.72,0.673-1.035 c0.315-0.315,0.615-0.51,1.035-0.673c0.317-0.123,0.794-0.27,1.671-0.31C9.312,4.631,9.597,4.622,12,4.622 M12,3 C9.556,3,9.249,3.01,8.289,3.054C7.331,3.098,6.677,3.25,6.105,3.472C5.513,3.702,5.011,4.01,4.511,4.511 c-0.5,0.5-0.808,1.002-1.038,1.594C3.25,6.677,3.098,7.331,3.054,8.289C3.01,9.249,3,9.556,3,12c0,2.444,0.01,2.751,0.054,3.711 c0.044,0.958,0.196,1.612,0.418,2.185c0.23,0.592,0.538,1.094,1.038,1.594c0.5,0.5,1.002,0.808,1.594,1.038 c0.572,0.222,1.227,0.375,2.185,0.418C9.249,20.99,9.556,21,12,21s2.751-0.01,3.711-0.054c0.958-0.044,1.612-0.196,2.185-0.418 c0.592-0.23,1.094-0.538,1.594-1.038c0.5-0.5,0.808-1.002,1.038-1.594c0.222-0.572,0.375-1.227,0.418-2.185 C20.99,14.751,21,14.444,21,12s-0.01-2.751-0.054-3.711c-0.044-0.958-0.196-1.612-0.418-2.185c-0.23-0.592-0.538-1.094-1.038-1.594 c-0.5-0.5-1.002-0.808-1.594-1.038c-0.572-0.222-1.227-0.375-2.185-0.418C14.751,3.01,14.444,3,12,3L12,3z M12,7.378 c-2.552,0-4.622,2.069-4.622,4.622S9.448,16.622,12,16.622s4.622-2.069,4.622-4.622S14.552,7.378,12,7.378z M12,15 c-1.657,0-3-1.343-3-3s1.343-3,3-3s3,1.343,3,3S13.657,15,12,15z M16.804,6.116c-0.596,0-1.08,0.484-1.08,1.08 s0.484,1.08,1.08,1.08c0.596,0,1.08-0.484,1.08-1.08S17.401,6.116,16.804,6.116z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Instagram<\/span><\/a><\/li>\r\n\r\n<li style=\"color:#2d3142\" class=\"wp-social-link wp-social-link-whatsapp has-headings-color wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/wa.me\/message\/C4HPKVOB2Y6KJ1\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M 12.011719 2 C 6.5057187 2 2.0234844 6.478375 2.0214844 11.984375 C 2.0204844 13.744375 2.4814687 15.462563 3.3554688 16.976562 L 2 22 L 7.2324219 20.763672 C 8.6914219 21.559672 10.333859 21.977516 12.005859 21.978516 L 12.009766 21.978516 C 17.514766 21.978516 21.995047 17.499141 21.998047 11.994141 C 22.000047 9.3251406 20.962172 6.8157344 19.076172 4.9277344 C 17.190172 3.0407344 14.683719 2.001 12.011719 2 z M 12.009766 4 C 14.145766 4.001 16.153109 4.8337969 17.662109 6.3417969 C 19.171109 7.8517969 20.000047 9.8581875 19.998047 11.992188 C 19.996047 16.396187 16.413812 19.978516 12.007812 19.978516 C 10.674812 19.977516 9.3544062 19.642812 8.1914062 19.007812 L 7.5175781 18.640625 L 6.7734375 18.816406 L 4.8046875 19.28125 L 5.2851562 17.496094 L 5.5019531 16.695312 L 5.0878906 15.976562 C 4.3898906 14.768562 4.0204844 13.387375 4.0214844 11.984375 C 4.0234844 7.582375 7.6067656 4 12.009766 4 z M 8.4765625 7.375 C 8.3095625 7.375 8.0395469 7.4375 7.8105469 7.6875 C 7.5815469 7.9365 6.9355469 8.5395781 6.9355469 9.7675781 C 6.9355469 10.995578 7.8300781 12.182609 7.9550781 12.349609 C 8.0790781 12.515609 9.68175 15.115234 12.21875 16.115234 C 14.32675 16.946234 14.754891 16.782234 15.212891 16.740234 C 15.670891 16.699234 16.690438 16.137687 16.898438 15.554688 C 17.106437 14.971687 17.106922 14.470187 17.044922 14.367188 C 16.982922 14.263188 16.816406 14.201172 16.566406 14.076172 C 16.317406 13.951172 15.090328 13.348625 14.861328 13.265625 C 14.632328 13.182625 14.464828 13.140625 14.298828 13.390625 C 14.132828 13.640625 13.655766 14.201187 13.509766 14.367188 C 13.363766 14.534188 13.21875 14.556641 12.96875 14.431641 C 12.71875 14.305641 11.914938 14.041406 10.960938 13.191406 C 10.218937 12.530406 9.7182656 11.714844 9.5722656 11.464844 C 9.4272656 11.215844 9.5585938 11.079078 9.6835938 10.955078 C 9.7955938 10.843078 9.9316406 10.663578 10.056641 10.517578 C 10.180641 10.371578 10.223641 10.267562 10.306641 10.101562 C 10.389641 9.9355625 10.347156 9.7890625 10.285156 9.6640625 C 10.223156 9.5390625 9.737625 8.3065 9.515625 7.8125 C 9.328625 7.3975 9.131125 7.3878594 8.953125 7.3808594 C 8.808125 7.3748594 8.6425625 7.375 8.4765625 7.375 z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">WhatsApp<\/span><\/a><\/li>\r\n\r\n<li style=\"color:#2d3142\" class=\"wp-social-link wp-social-link-mail has-headings-color wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"mailto:&#105;n&#102;&#111;&#064;&#114;&#105;&#097;&#100;a&#098;&#097;di&#046;&#099;o&#109;\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19,5H5c-1.1,0-2,.9-2,2v10c0,1.1.9,2,2,2h14c1.1,0,2-.9,2-2V7c0-1.1-.9-2-2-2zm.5,12c0,.3-.2.5-.5.5H5c-.3,0-.5-.2-.5-.5V9.8l7.5,5.6,7.5-5.6V17zm0-9.1L12,13.6,4.5,7.9V7c0-.3.2-.5.5-.5h14c.3,0,.5.2.5.5v.9z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Mail<\/span><\/a><\/li><\/ul>\r\n","protected":false},"excerpt":{"rendered":"<p>Evoluez au coeur d&#8217;une cit\u00e9 m\u00e9di\u00e9vale encore en activit\u00e9 La vieille ville de F\u00e8s, la m\u00e9dina, est le plus grand &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_crdt_document":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-222","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/riadabadi.com\/index.php\/wp-json\/wp\/v2\/pages\/222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riadabadi.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/riadabadi.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/riadabadi.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/riadabadi.com\/index.php\/wp-json\/wp\/v2\/comments?post=222"}],"version-history":[{"count":26,"href":"https:\/\/riadabadi.com\/index.php\/wp-json\/wp\/v2\/pages\/222\/revisions"}],"predecessor-version":[{"id":624,"href":"https:\/\/riadabadi.com\/index.php\/wp-json\/wp\/v2\/pages\/222\/revisions\/624"}],"wp:attachment":[{"href":"https:\/\/riadabadi.com\/index.php\/wp-json\/wp\/v2\/media?parent=222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}